{"id":319,"count":1,"description":"","link":"https:\/\/www.patedds.com\/blog\/tag\/buckhead-dental-health\/","name":"buckhead dental health","slug":"buckhead-dental-health","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.patedds.com\/blog\/wp-json\/wp\/v2\/tags\/319"}],"collection":[{"href":"https:\/\/www.patedds.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.patedds.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.patedds.com\/blog\/wp-json\/wp\/v2\/posts?tags=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}